{"id":39024,"date":"2025-12-04T08:10:04","date_gmt":"2025-12-04T07:10:04","guid":{"rendered":"https:\/\/salentoprime.com\/strutture\/villa-rosa-villa-antares-pescoluse-copy\/"},"modified":"2026-05-27T22:21:00","modified_gmt":"2026-05-27T20:21:00","slug":"villa-aura-maris-with-pool","status":"publish","type":"tf_apartment","link":"https:\/\/salentoprime.com\/en\/properties\/villa-aura-maris-with-pool\/","title":{"rendered":"Villa Aura Maris with pool"},"content":{"rendered":"","protected":false},"author":3,"featured_media":39030,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"struttura":[123],"apartment_location":[161,137],"apartment_feature":[175,171,101,162,164,176,100,172,173,165,174,158,159,127],"apartment_type":[],"class_list":["post-39024","tf_apartment","type-tf_apartment","status-publish","has-post-thumbnail","hentry","struttura-ville","apartment_location-hot-deals","apartment_location-pescoluse","apartment_feature-2-o-piu-bagni","apartment_feature-animali-ammessi","apartment_feature-aria-condizionata","apartment_feature-barbecue","apartment_feature-caminetto","apartment_feature-casa-in-campagna-natura","apartment_feature-cucina-completa","apartment_feature-fronte-mare","apartment_feature-giardino","apartment_feature-lavatrice","apartment_feature-meno-di-1-km-dal-mare","apartment_feature-parcheggio-privato","apartment_feature-piscina","apartment_feature-tv-a-schermo-piatto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Villa Aura Maris con piscina - Salento Prime<\/title>\n<meta name=\"description\" content=\"La villa accoglie gli ospiti in una luminosa zona living ricavata all\u2019interno di un tipico trullo salentino, dove la pietra locale, le volte caratteristiche e i dettagli artigianali creano un\u2019atmosfera unica e autentica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salentoprime.com\/en\/properties\/villa-aura-maris-with-pool\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Aura Maris con piscina - Salento Prime\" \/>\n<meta property=\"og:description\" content=\"La villa accoglie gli ospiti in una luminosa zona living ricavata all\u2019interno di un tipico trullo salentino, dove la pietra locale, le volte caratteristiche e i dettagli artigianali creano un\u2019atmosfera unica e autentica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salentoprime.com\/en\/properties\/villa-aura-maris-with-pool\/\" \/>\n<meta property=\"og:site_name\" content=\"Salento Prime\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-27T20:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/\",\"url\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/\",\"name\":\"Villa Aura Maris con piscina - Salento Prime\",\"isPartOf\":{\"@id\":\"https:\/\/salentoprime.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp\",\"datePublished\":\"2025-12-04T07:10:04+00:00\",\"dateModified\":\"2026-05-27T20:21:00+00:00\",\"description\":\"La villa accoglie gli ospiti in una luminosa zona living ricavata all\u2019interno di un tipico trullo salentino, dove la pietra locale, le volte caratteristiche e i dettagli artigianali creano un\u2019atmosfera unica e autentica.\",\"breadcrumb\":{\"@id\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#primaryimage\",\"url\":\"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp\",\"contentUrl\":\"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/salentoprime.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apartments\",\"item\":\"https:\/\/salentoprime.com\/apartments\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa Aura Maris con piscina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/salentoprime.com\/#website\",\"url\":\"https:\/\/salentoprime.com\/\",\"name\":\"Salento Prime\",\"description\":\"Property Manager\",\"publisher\":{\"@id\":\"https:\/\/salentoprime.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/salentoprime.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/salentoprime.com\/#organization\",\"name\":\"Salento Prime srl\",\"url\":\"https:\/\/salentoprime.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/salentoprime.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/salentoprime.com\/wp-content\/uploads\/2024\/04\/SalentoPRIME_logo_V_colore_negativo_RGB@4x.webp\",\"contentUrl\":\"https:\/\/salentoprime.com\/wp-content\/uploads\/2024\/04\/SalentoPRIME_logo_V_colore_negativo_RGB@4x.webp\",\"width\":1701,\"height\":1702,\"caption\":\"Salento Prime srl\"},\"image\":{\"@id\":\"https:\/\/salentoprime.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/salentoprime\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Aura Maris con piscina - Salento Prime","description":"La villa accoglie gli ospiti in una luminosa zona living ricavata all\u2019interno di un tipico trullo salentino, dove la pietra locale, le volte caratteristiche e i dettagli artigianali creano un\u2019atmosfera unica e autentica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salentoprime.com\/en\/properties\/villa-aura-maris-with-pool\/","og_locale":"en_US","og_type":"article","og_title":"Villa Aura Maris con piscina - Salento Prime","og_description":"La villa accoglie gli ospiti in una luminosa zona living ricavata all\u2019interno di un tipico trullo salentino, dove la pietra locale, le volte caratteristiche e i dettagli artigianali creano un\u2019atmosfera unica e autentica.","og_url":"https:\/\/salentoprime.com\/en\/properties\/villa-aura-maris-with-pool\/","og_site_name":"Salento Prime","article_modified_time":"2026-05-27T20:21:00+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/","url":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/","name":"Villa Aura Maris con piscina - Salento Prime","isPartOf":{"@id":"https:\/\/salentoprime.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#primaryimage"},"image":{"@id":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#primaryimage"},"thumbnailUrl":"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp","datePublished":"2025-12-04T07:10:04+00:00","dateModified":"2026-05-27T20:21:00+00:00","description":"La villa accoglie gli ospiti in una luminosa zona living ricavata all\u2019interno di un tipico trullo salentino, dove la pietra locale, le volte caratteristiche e i dettagli artigianali creano un\u2019atmosfera unica e autentica.","breadcrumb":{"@id":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#primaryimage","url":"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp","contentUrl":"https:\/\/salentoprime.com\/wp-content\/uploads\/2025\/12\/2025_11_13-salento_prime-t.Pali@001.webp","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/salentoprime.com\/strutture\/villa-aura-maris-con-piscina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salentoprime.com\/"},{"@type":"ListItem","position":2,"name":"Apartments","item":"https:\/\/salentoprime.com\/apartments\/"},{"@type":"ListItem","position":3,"name":"Villa Aura Maris con piscina"}]},{"@type":"WebSite","@id":"https:\/\/salentoprime.com\/#website","url":"https:\/\/salentoprime.com\/","name":"Salento Prime","description":"Property Manager","publisher":{"@id":"https:\/\/salentoprime.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salentoprime.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/salentoprime.com\/#organization","name":"Salento Prime srl","url":"https:\/\/salentoprime.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/salentoprime.com\/#\/schema\/logo\/image\/","url":"https:\/\/salentoprime.com\/wp-content\/uploads\/2024\/04\/SalentoPRIME_logo_V_colore_negativo_RGB@4x.webp","contentUrl":"https:\/\/salentoprime.com\/wp-content\/uploads\/2024\/04\/SalentoPRIME_logo_V_colore_negativo_RGB@4x.webp","width":1701,"height":1702,"caption":"Salento Prime srl"},"image":{"@id":"https:\/\/salentoprime.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/salentoprime\/"]}]}},"_links":{"self":[{"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/tf_apartment\/39024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/tf_apartment"}],"about":[{"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/types\/tf_apartment"}],"author":[{"embeddable":true,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":6,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/tf_apartment\/39024\/revisions"}],"predecessor-version":[{"id":39112,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/tf_apartment\/39024\/revisions\/39112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/media\/39030"}],"wp:attachment":[{"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/media?parent=39024"}],"wp:term":[{"taxonomy":"struttura","embeddable":true,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/struttura?post=39024"},{"taxonomy":"apartment_location","embeddable":true,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/apartment_location?post=39024"},{"taxonomy":"apartment_feature","embeddable":true,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/apartment_feature?post=39024"},{"taxonomy":"apartment_type","embeddable":true,"href":"https:\/\/salentoprime.com\/en\/wp-json\/wp\/v2\/apartment_type?post=39024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}